{"id":2070,"date":"2012-06-27T09:23:28","date_gmt":"2012-06-27T13:53:28","guid":{"rendered":"http:\/\/www.tubrica.com\/?p=2070"},"modified":"2020-09-28T20:29:32","modified_gmt":"2020-09-28T20:29:32","slug":"induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia","status":"publish","type":"post","link":"https:\/\/tubrica.com\/en\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/","title":{"rendered":"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia"},"content":{"rendered":"<div>\n<p><span style=\"font-family: Calibri; font-size: small;\">En TUBRICA nos preocupamos constantemente por brindar el mejor servicio a todos los niveles de nuestra organizaci\u00f3n.\u00a0 Por esta raz\u00f3n, constantemente desarrollamos talleres dirigidos al personal de nuestros distribuidores, a fin de garantizar que el usuario final reciba la mejor asesor\u00eda a la hora de seleccionar el producto m\u00e1s adecuado para su necesidad.\u00a0 El pasado d\u00eda Jueves 21 de Junio al personal de ACERO OFERTA en Catia, Caracas, se le dict\u00f3 una inducci\u00f3n referente a los productos de las l\u00edneas de Edificaciones, que comprenden tubosistemas para instalaciones de: presi\u00f3n agua fr\u00eda y agua caliente, sanitarias y el\u00e9ctricas. \u00a0De esta manera TUBRICA continua con su campa\u00f1a de divulgaci\u00f3n y formaci\u00f3n en materia de tubosistemas de PVC, a fin de garantizar que nuestros clientes reciban siempre la mejor calidad y el mejor servicio.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2071\" title=\"acero oferta 01\" src=\"http:\/\/tubrica.ignitecore.io\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg\" alt=\"\" width=\"220\" height=\"120\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En TUBRICA nos preocupamos constantemente por brindar el mejor servicio a todos los niveles de nuestra organizaci\u00f3n.\u00a0 Por esta raz\u00f3n, constantemente desarrollamos talleres dirigidos al personal de nuestros distribuidores, a fin de garantizar que el usuario final reciba la mejor asesor\u00eda a la hora de seleccionar el producto m\u00e1s adecuado para su necesidad.\u00a0 El pasado d\u00eda Jueves 21 de Junio al personal de ACERO OFERTA en Catia, Caracas, se le dict\u00f3 una inducci\u00f3n referente a los productos de las l\u00edneas de Edificaciones, que comprenden tubosistemas para instalaciones de: presi\u00f3n agua fr\u00eda y agua caliente, sanitarias y el\u00e9ctricas. \u00a0De esta manera TUBRICA continua con su campa\u00f1a de divulgaci\u00f3n y formaci\u00f3n en materia de tubosistemas de PVC, a fin de garantizar que nuestros clientes reciban siempre la mejor calidad y el mejor servicio. &nbsp; &nbsp; &nbsp;<\/p>","protected":false},"author":2,"featured_media":7183,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[163],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia - Tubrica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tubrica.com\/en\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia - Tubrica\" \/>\n<meta property=\"og:description\" content=\"En TUBRICA nos preocupamos constantemente por brindar el mejor servicio a todos los niveles de nuestra organizaci\u00f3n.\u00a0 Por esta raz\u00f3n, constantemente desarrollamos talleres dirigidos al personal de nuestros distribuidores, a fin de garantizar que el usuario final reciba la mejor asesor\u00eda a la hora de seleccionar el producto m\u00e1s adecuado para su necesidad.\u00a0 El pasado d\u00eda Jueves 21 de Junio al personal de ACERO OFERTA en Catia, Caracas, se le dict\u00f3 una inducci\u00f3n referente a los productos de las l\u00edneas de Edificaciones, que comprenden tubosistemas para instalaciones de: presi\u00f3n agua fr\u00eda y agua caliente, sanitarias y el\u00e9ctricas. \u00a0De esta manera TUBRICA continua con su campa\u00f1a de divulgaci\u00f3n y formaci\u00f3n en materia de tubosistemas de PVC, a fin de garantizar que nuestros clientes reciban siempre la mejor calidad y el mejor servicio. &nbsp; &nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tubrica.com\/en\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/\" \/>\n<meta property=\"og:site_name\" content=\"Tubrica\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-27T13:53:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-28T20:29:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"220\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tubrica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tubrica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/\"},\"author\":{\"name\":\"Tubrica\",\"@id\":\"https:\/\/tubrica.com\/#\/schema\/person\/b78eb408189ac83661b8d66e8f4a4346\"},\"headline\":\"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia\",\"datePublished\":\"2012-06-27T13:53:28+00:00\",\"dateModified\":\"2020-09-28T20:29:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/\"},\"wordCount\":163,\"publisher\":{\"@id\":\"https:\/\/tubrica.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/\",\"url\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/\",\"name\":\"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia - Tubrica\",\"isPartOf\":{\"@id\":\"https:\/\/tubrica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg\",\"datePublished\":\"2012-06-27T13:53:28+00:00\",\"dateModified\":\"2020-09-28T20:29:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#primaryimage\",\"url\":\"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg\",\"contentUrl\":\"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg\",\"width\":220,\"height\":120},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tubrica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tubrica.com\/#website\",\"url\":\"https:\/\/tubrica.com\/\",\"name\":\"Tubrica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/tubrica.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tubrica.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tubrica.com\/#organization\",\"name\":\"Tubrica\",\"url\":\"https:\/\/tubrica.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tubrica.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/04\/LOGO_TUBRICA_350x100.png\",\"contentUrl\":\"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/04\/LOGO_TUBRICA_350x100.png\",\"width\":1459,\"height\":417,\"caption\":\"Tubrica\"},\"image\":{\"@id\":\"https:\/\/tubrica.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/tubrica.com\/#\/schema\/person\/b78eb408189ac83661b8d66e8f4a4346\",\"name\":\"Tubrica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tubrica.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d2f4acb381f732f9ef565884327a3c28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d2f4acb381f732f9ef565884327a3c28?s=96&d=mm&r=g\",\"caption\":\"Tubrica\"},\"url\":\"https:\/\/tubrica.com\/en\/author\/angel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia - Tubrica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tubrica.com\/en\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/","og_locale":"en_US","og_type":"article","og_title":"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia - Tubrica","og_description":"En TUBRICA nos preocupamos constantemente por brindar el mejor servicio a todos los niveles de nuestra organizaci\u00f3n.\u00a0 Por esta raz\u00f3n, constantemente desarrollamos talleres dirigidos al personal de nuestros distribuidores, a fin de garantizar que el usuario final reciba la mejor asesor\u00eda a la hora de seleccionar el producto m\u00e1s adecuado para su necesidad.\u00a0 El pasado d\u00eda Jueves 21 de Junio al personal de ACERO OFERTA en Catia, Caracas, se le dict\u00f3 una inducci\u00f3n referente a los productos de las l\u00edneas de Edificaciones, que comprenden tubosistemas para instalaciones de: presi\u00f3n agua fr\u00eda y agua caliente, sanitarias y el\u00e9ctricas. \u00a0De esta manera TUBRICA continua con su campa\u00f1a de divulgaci\u00f3n y formaci\u00f3n en materia de tubosistemas de PVC, a fin de garantizar que nuestros clientes reciban siempre la mejor calidad y el mejor servicio. &nbsp; &nbsp; &nbsp;","og_url":"https:\/\/tubrica.com\/en\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/","og_site_name":"Tubrica","article_published_time":"2012-06-27T13:53:28+00:00","article_modified_time":"2020-09-28T20:29:32+00:00","og_image":[{"width":220,"height":120,"url":"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg","type":"image\/jpeg"}],"author":"Tubrica","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tubrica","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#article","isPartOf":{"@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/"},"author":{"name":"Tubrica","@id":"https:\/\/tubrica.com\/#\/schema\/person\/b78eb408189ac83661b8d66e8f4a4346"},"headline":"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia","datePublished":"2012-06-27T13:53:28+00:00","dateModified":"2020-09-28T20:29:32+00:00","mainEntityOfPage":{"@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/"},"wordCount":163,"publisher":{"@id":"https:\/\/tubrica.com\/#organization"},"image":{"@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#primaryimage"},"thumbnailUrl":"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg","articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/","url":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/","name":"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia - Tubrica","isPartOf":{"@id":"https:\/\/tubrica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#primaryimage"},"image":{"@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#primaryimage"},"thumbnailUrl":"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg","datePublished":"2012-06-27T13:53:28+00:00","dateModified":"2020-09-28T20:29:32+00:00","breadcrumb":{"@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#primaryimage","url":"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg","contentUrl":"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/09\/acero-oferta-01-220x120.jpg","width":220,"height":120},{"@type":"BreadcrumbList","@id":"https:\/\/tubrica.com\/induccion-de-la-lineas-de-edificaciones-para-el-personal-de-acero-oferta-en-catia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tubrica.com\/"},{"@type":"ListItem","position":2,"name":"Inducci\u00f3n de los productos del segmento de Edificaciones para el personal de ACERO OFERTA en Catia"}]},{"@type":"WebSite","@id":"https:\/\/tubrica.com\/#website","url":"https:\/\/tubrica.com\/","name":"Tubrica","description":"","publisher":{"@id":"https:\/\/tubrica.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tubrica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tubrica.com\/#organization","name":"Tubrica","url":"https:\/\/tubrica.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tubrica.com\/#\/schema\/logo\/image\/","url":"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/04\/LOGO_TUBRICA_350x100.png","contentUrl":"https:\/\/tubrica.com\/wp-content\/uploads\/2020\/04\/LOGO_TUBRICA_350x100.png","width":1459,"height":417,"caption":"Tubrica"},"image":{"@id":"https:\/\/tubrica.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tubrica.com\/#\/schema\/person\/b78eb408189ac83661b8d66e8f4a4346","name":"Tubrica","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tubrica.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d2f4acb381f732f9ef565884327a3c28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2f4acb381f732f9ef565884327a3c28?s=96&d=mm&r=g","caption":"Tubrica"},"url":"https:\/\/tubrica.com\/en\/author\/angel\/"}]}},"_links":{"self":[{"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/posts\/2070"}],"collection":[{"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/comments?post=2070"}],"version-history":[{"count":0,"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/posts\/2070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/media\/7183"}],"wp:attachment":[{"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/media?parent=2070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/categories?post=2070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tubrica.com\/en\/wp-json\/wp\/v2\/tags?post=2070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}